{"id":26917,"date":"2022-12-12T15:56:46","date_gmt":"2022-12-12T18:56:46","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=26917"},"modified":"2022-12-12T15:56:57","modified_gmt":"2022-12-12T18:56:57","slug":"anses-inicio-el-pago-de-la-segunda-cuota-del-refuerzo-alimentario","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/anses-inicio-el-pago-de-la-segunda-cuota-del-refuerzo-alimentario\/","title":{"rendered":"ANSES: inici\u00f3 el pago de la segunda cuota del refuerzo alimentario"},"content":{"rendered":"\n<p>Se trata de un beneficio \u00fanicamente para adultos sin ingresos. Ser\u00e1 de acuerdo a la terminaci\u00f3n del DNI.<\/p>\n\n\n\n<p>A su vez, aquellas personas que ya tienen su inscripci\u00f3n aprobada en el aplicativo, pero no ercibieron el pago en el calendario anterior, este mes<strong>&nbsp;cobrar\u00e1n las dos cuotas juntas correspondientes al Refuerzo.&nbsp;<\/strong><\/p>\n\n\n\n<p>Asimismo, ANSES comunicar\u00e1 desde sus canales oficiales a las personas que realizaron un reclamo en las oficinas del organismo (y hayan tenido una respuesta favorable) para informarles la fecha de cobro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El cronograma de pago:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>DNI terminado en 0: 12 de diciembre<\/li><li>DNI terminado en 1: 13 de diciembre<\/li><li>DNI terminado en 2: 14 de diciembre<\/li><li>DNI terminado en 3: 15 de diciembre<\/li><li>DNI terminado en 4: 16 de diciembre<\/li><li>DNI terminado en 5: 19 de diciembre<\/li><li>DNI terminado en 6: 20 de diciembre<\/li><li>DNI terminado en 7: 21 de diciembre<\/li><li>DNI terminado en 8: 22 de diciembre<\/li><li>DNI terminado en 9: 23 de diciembre<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un beneficio \u00fanicamente para adultos sin ingresos. Ser\u00e1 de acuerdo a la terminaci\u00f3n del DNI. A su vez, aquellas personas que ya tienen su inscripci\u00f3n aprobada en&hellip; <\/p>\n","protected":false},"author":8,"featured_media":26918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-26917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/26917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=26917"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/26917\/revisions"}],"predecessor-version":[{"id":26919,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/26917\/revisions\/26919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/26918"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=26917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=26917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=26917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}