{"id":29108,"date":"2022-12-21T22:49:43","date_gmt":"2022-12-22T01:49:43","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=29108"},"modified":"2022-12-21T22:49:49","modified_gmt":"2022-12-22T01:49:49","slug":"la-reflexion-de-coti-tras-su-feroz-pelea-con-romina-y-julieta","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/la-reflexion-de-coti-tras-su-feroz-pelea-con-romina-y-julieta\/","title":{"rendered":"La reflexi\u00f3n de Coti tras su feroz pelea con Romina y Julieta"},"content":{"rendered":"\n<p>Luego de su feroz pelea con Romina y Julieta, Coti se dirigi\u00f3 a la habitaci\u00f3n de las mujeres y reflexion\u00f3 en voz alta al respecto.<\/p>\n\n\n\n<p><strong>&#8220;Qu\u00e9 lealtad ni que nada&#8230; Nunca, jam\u00e1s, jugu\u00e9 con ustedes, idiotas. No le debo lealtad a ninguna&#8221;<\/strong>&nbsp;, dispar\u00f3 la correntina, quien le hizo la nominaci\u00f3n espont\u00e1nea a sus compa\u00f1eras, algo que desemboc\u00f3 en la salida de Daniela.<\/p>\n\n\n\n<p>Antes de decir esto, y una vez finalizada la pela con las chicas, Alfa le dio un papel higi\u00e9nico en la mano para molestarla porque la hab\u00edan acusado de tener la cola sucia.\u00a0<\/p>\n\n\n\n<p>Lejos de enojarse o tom\u00e1rselo mal, Coti cort\u00f3 un poco de papel e hizo el gesto de limpiarse.&nbsp;<strong>&#8220;Dame, me lo limpio, me lo limpio&#8230; Dios m\u00edo, lo que faltaba&#8221;<\/strong>&nbsp;, cerr\u00f3 mientras apoy\u00f3 el papel en la mesa.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de su feroz pelea con Romina y Julieta, Coti se dirigi\u00f3 a la habitaci\u00f3n de las mujeres y reflexion\u00f3 en voz alta al respecto. &#8220;Qu\u00e9 lealtad ni que nada&#8230;&hellip; <\/p>\n","protected":false},"author":1,"featured_media":29115,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-29108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=29108"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29108\/revisions"}],"predecessor-version":[{"id":29116,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29108\/revisions\/29116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/29115"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=29108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=29108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=29108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}