{"id":29902,"date":"2022-12-26T19:33:42","date_gmt":"2022-12-26T22:33:42","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=29902"},"modified":"2022-12-26T19:33:46","modified_gmt":"2022-12-26T22:33:46","slug":"came-registro-5-meses-de-caida-consecutiva-en-distintos-rubros","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/came-registro-5-meses-de-caida-consecutiva-en-distintos-rubros\/","title":{"rendered":"Came registr\u00f3 5 meses de ca\u00edda consecutiva en distintos rubros"},"content":{"rendered":"\n<p>Salvador Femen\u00eda, vocero de CAME, dialog\u00f3 y se refiri\u00f3 a las ventas navide\u00f1as y la situaci\u00f3n de las pymes en un contexto de crisis econ\u00f3mica e inflaci\u00f3n. Anticiparon que, en promedio en todo el pa\u00eds, se registr\u00f3 una ca\u00edda del 1,8 por ciento.<\/p>\n\n\n\n<p>Seg\u00fan el relevamiento de la CAME, las ventas navide\u00f1as en 2022 estuvieron por debajo de las del a\u00f1o pasado.&nbsp;<strong>En promedio en todo el pa\u00eds, se registr\u00f3 una ca\u00edda del 1,8 por ciento y aseguran que registr\u00f3 5 meses de ca\u00edda consecutiva en distintos rubros.<\/strong><\/p>\n\n\n\n<p>\u201cEstamos hablando dentro de un contexto econ\u00f3mico donde hay una evidente p\u00e9rdida de poder adquisitivo y la falta de tiempo por el mundial. Recordemos que el martes fue feriado y est\u00e1bamos en la semana previa de las fiestas\u201d,&nbsp;<strong>indic\u00f3 Salvador Femen\u00eda, vocero de CAME.<\/strong><\/p>\n\n\n\n<p>\u201cEn los \u00faltimos 5 meses se siente una ca\u00edda en los distintos rubros en t\u00e9rminos generales. El mes que no se registr\u00f3 una ca\u00edda fue junio por el D\u00eda del Padre. Pero esta situaci\u00f3n actual tiene que ver con los \u00edndices de inflaci\u00f3n que termin\u00f3 mellando el poder adquisitivo\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>El informe de la CAME fue elaborado por unos 30 encuestadores de todo el pa\u00eds que relevaron comercios durante el 23 y el 24 de diciembre. De los 6 grandes rubros analizados, crecieron Cosm\u00e9tica y Perfumer\u00eda (+2,1%), Equipos de audio, video, celulares y accesorios (+4,2%) y Jugueter\u00edas (+3,4%) y cayeron Calzados (-5,1%), Indumentaria (-14,4%) y Librer\u00edas (-7,5%).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Radiograf\u00eda de las ventas navide\u00f1as en 2022<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>El ticket promedio se ubic\u00f3 en $9.410, con el monto m\u00e1s elevado en Audio, Video, Celulares y Accesorios ($10.985) y el m\u00e1s bajo en Librer\u00edas ($5.222).<\/li><li>Al 76,8% de los comercios medidos les fue igual o mejor de lo esperado, 3,6 puntos porcentuales por encima del a\u00f1o pasado (73,2%).<\/li><li>Por los m\u00e1rgenes m\u00e1s ajustados y cierta incertidumbre sobre los costos de reposici\u00f3n de la mercader\u00eda posfiestas, hubo escasez de promociones.<\/li><li>Solo la mitad de los negocios de la muestra realiz\u00f3 alguna, cuando en 2021 casi el 70% de estos ofrecieron algo.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Salvador Femen\u00eda, vocero de CAME, dialog\u00f3 y se refiri\u00f3 a las ventas navide\u00f1as y la situaci\u00f3n de las pymes en un contexto de crisis econ\u00f3mica e inflaci\u00f3n. Anticiparon que, en&hellip; <\/p>\n","protected":false},"author":8,"featured_media":29903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-29902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=29902"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29902\/revisions"}],"predecessor-version":[{"id":29904,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/29902\/revisions\/29904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/29903"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=29902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=29902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=29902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}