{"id":30054,"date":"2022-12-27T14:18:44","date_gmt":"2022-12-27T17:18:44","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=30054"},"modified":"2022-12-27T14:18:48","modified_gmt":"2022-12-27T17:18:48","slug":"dolar-hoy-en-vivo-la-cotizacion-libre-sube-a-355-y-marca-un-nuevo-record-nominal","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/nacionales\/dolar-hoy-en-vivo-la-cotizacion-libre-sube-a-355-y-marca-un-nuevo-record-nominal\/","title":{"rendered":"D\u00f3lar hoy en vivo: la cotizaci\u00f3n libre sube a $355 y marca un nuevo r\u00e9cord nominal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El d\u00f3lar \u201cblue\u201d avanza nueve pesos o un 2,6% en el d\u00eda. En lo que va de diciembre suma un incremento de 41 pesos o un 13%<\/h2>\n\n\n\n<p>12:51&nbsp;HsHOY<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El d\u00f3lar libre escala a 355 pesos<\/h2>\n\n\n\n<p>El d\u00f3lar libre encadena este martes la cuarta rueda operativa en alza en forma consecutiva. Evidentemente la demanda por el billete se increment\u00f3 en los \u00faltimos d\u00edas y as\u00ed alcanz\u00f3 los<strong>&nbsp;$355 para la venta, un r\u00e9cord&nbsp;<\/strong>hist\u00f3rico nominal.<\/p>\n\n\n\n<p>As\u00ed, el d\u00f3lar \u201cblue\u201d avanza nueve pesos o un 2,6% en el d\u00eda. En lo que va de diciembre suma un incremento de 41 pesos o un 13 por ciento. En tanto, el billete informal ampl\u00eda las ganancias acumuladas a lo largo de 2022 a 70,7%, aun por debajo de lo que fue la inflaci\u00f3n del per\u00edodo.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"El d\u00f3lar libre supera a la inflaci\u00f3n en el \u00faltimo mes del a\u00f1o.\" height=\"1080\" width=\"1920\" class=\"\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/M0P2V_0ejOrQRdjwvaQFiwglXpg=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/BkGyR-cLcI0DAhHK_U48pNRKLl8=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/g16uMcMrionCtzN9TH42QfKWBm4=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/DySRBhGCPZRj6RvbcpHqggQTooQ=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/98ZiSAKiIBza0QxYkVZaZ4bvLrw=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CSWJEYS76BFNFJJ6M5L6FDX3YI.jpg 1440w\">El d\u00f3lar libre supera a la inflaci\u00f3n en el \u00faltimo mes del a\u00f1o.<\/p>\n\n\n\n<p>11:29&nbsp;HsHOY<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los d\u00f3lares burs\u00e1tiles, en zona de m\u00e1ximos<\/h2>\n\n\n\n<p>Las paridades del d\u00f3lar que se obtienen en la Bolsa a trav\u00e9s de la operatoria con bonos tambi\u00e9n se pactan con tendencia alcista, aunque algo moderada en comparaci\u00f3n al d\u00f3lar libre. El \u201ccontado con liquidaci\u00f3n\u201d a trav\u00e9s del bono Global 2030 (GD30C) sube a $338, mientras que el d\u00f3lar MEP con el Bonar 2030 (AL30D) se negocia en torno a $332. En ambos casos, cerca de sus valores m\u00e1ximos de loa \u00faltima semana de julio.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Los d\u00f3lares alternativos cierran el 2022 en alza.\" height=\"800\" width=\"1200\" class=\"\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/IAeQVUsMGjKklTG8UGY1yf9bqwg=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/HQmZAs-gK2lMgVHeJPpYDPOaJYo=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/eYTZjHY7l7nHVek3kWtbK_ra_UQ=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/JNp5f86sC-REnzCrJgkflGRLQRI=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/GpzDfMcR5fAnZ8rYuP6vXiyP2bk=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JH6WUCPS6RCBTDFXR5FZF2FVMI.jpg 1440w\">Los d\u00f3lares alternativos cierran el 2022 en alza.<\/p>\n\n\n\n<p>11:23&nbsp;HsHOY<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El d\u00f3lar libre sube a 352 pesos<\/h2>\n\n\n\n<p>El billete negociado en el mercado marginal sube por cuarta sesi\u00f3n consecutiva. Este martes gana seis pesos o un 1,7%, con lo que ampl\u00eda a 38 pesos o un 12,1% el avance del mes de diciembre. El d\u00f3lar \u201cblue\u201d registra as\u00ed un nuevo r\u00e9cord nominal, por encima del m\u00e1ximo intradiario de $350 del pasado 22 de julio, cinco meses atr\u00e1s.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"En diciembre el d\u00f3lar libre sube bien por encima d ela inflaci\u00f3n.\" height=\"242\" width=\"430\" class=\"\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/dlG8DHWKVHfq9VXMjVOJlUS9rDw=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png 420w,https:\/\/www.infobae.com\/new-resizer\/uE4ZzjxmXu04wQBaCDlDHa3kYLw=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png 768w,https:\/\/www.infobae.com\/new-resizer\/MH2-49dwjRlL40lOQuX2ngtyM4s=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png 992w,https:\/\/www.infobae.com\/new-resizer\/V_-l0Fm7ZwHUqSrK1aUpXH9MT3c=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png 1200w,https:\/\/www.infobae.com\/new-resizer\/i6IAiRXAaW_7dxHsPc0AYnh7NUo=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/DYKDXEPT2RGGXLREBUMCWWRVS4.png 1440w\">En diciembre el d\u00f3lar libre sube bien por encima d ela inflaci\u00f3n.<\/p>\n\n\n\n<p>10:34&nbsp;HsHOY<\/p>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/economia\/2022\/12\/27\/el-ultimo-de-la-tabla-el-billete-argentino-de-mayor-denominacion-es-el-menos-valioso-en-dolares-entre-13-paises-de-america\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.infobae.com\/economia\/2022\/12\/27\/el-ultimo-de-la-tabla-el-billete-argentino-de-mayor-denominacion-es-el-menos-valioso-en-dolares-entre-13-paises-de-america\/\" target=\"_blank\" rel=\"noreferrer noopener\">El \u00faltimo de la tabla: el billete argentino de mayor denominaci\u00f3n es el menos valioso en d\u00f3lares entre 13 pa\u00edses de Am\u00e9rica<\/a><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Considerado al tipo de cambio libre, el papel de 1.000 pesos argentinos equivale a 2,89 d\u00f3lares. Producto de la inflaci\u00f3n y de la negativa oficial a imprimir uno de mayor valor, es el de m\u00e1s bajo poder adquisitivo en la regi\u00f3n<\/h3>\n\n\n\n<p>27 de Diciembre de 2022<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"En mayo pasado, el BCRA anunci\u00f3 que trabaja en una nueva l\u00ednea de billetes para reemplazar animales por pr\u00f3ceres y figuras p\u00fablicas. Pero no se eval\u00faa un billete de 5.000 o 10.000 pesos (Adri\u00e1n Escandar)\" height=\"1080\" width=\"1920\" class=\"\" src=\"https:\/\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/RpXOlRrchpKyXuM5bH4236Qte6Q=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/A_t9Erv8_RMM40K4gEpmr06mNAQ=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/_eB1pcajxCgJoTOwGE2IsOJDc6s=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/MQz2W6hgvBPFUHMLkOuAaO-61QQ=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/x7R52n6VDzHAidir8G13puuQz8Q=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/U3TLC6YJFBBGPL7ORK6Z5HSHS4.jpg 1440w\">En mayo pasado, el BCRA anunci\u00f3 que trabaja en una nueva l\u00ednea de billetes para reemplazar animales por pr\u00f3ceres y figuras p\u00fablicas. Pero no se eval\u00faa un billete de 5.000 o 10.000 pesos (Adri\u00e1n Escandar)<\/p>\n\n\n\n<p>Por el impacto de la inflaci\u00f3n, la Argentina se acerca a un triste r\u00e9cord. En un relevamiento entre 13 pa\u00edses de la regi\u00f3n, su billete de mayor denominaci\u00f3n es el que menos valor tiene medido en d\u00f3lares. De esa forma, el papel de 1.000 pesos con la imagen del hornero es el que tiene un poder de compra m\u00e1s limitado en todo Am\u00e9rica, sin que adem\u00e1s existan planes a la vista para poner en circulaci\u00f3n alg\u00fan billete de una denominaci\u00f3n mayor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00f3lar \u201cblue\u201d avanza nueve pesos o un 2,6% en el d\u00eda. En lo que va de diciembre suma un incremento de 41 pesos o un 13% 12:51&nbsp;HsHOY El d\u00f3lar&hellip; <\/p>\n","protected":false},"author":1,"featured_media":30055,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-30054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=30054"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30054\/revisions"}],"predecessor-version":[{"id":30056,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30054\/revisions\/30056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/30055"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=30054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=30054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=30054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}