{"id":30107,"date":"2022-12-27T16:36:50","date_gmt":"2022-12-27T19:36:50","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=30107"},"modified":"2022-12-27T16:36:54","modified_gmt":"2022-12-27T19:36:54","slug":"aseguran-que-gerard-pique-dejo-a-shakira-porque-no-pudieron-tener-una-hija-ella-no-lo-logro","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/aseguran-que-gerard-pique-dejo-a-shakira-porque-no-pudieron-tener-una-hija-ella-no-lo-logro\/","title":{"rendered":"Aseguran que Gerard Piqu\u00e9 dej\u00f3 a Shakira porque no pudieron tener una hija: \u201cElla no lo logr\u00f3\u201d"},"content":{"rendered":"\n<p>La cantante ten\u00eda muchas ganas de cumplirle el deseo al futbolista, y se someti\u00f3 a varios tratamientos que no funcionaron.<\/p>\n\n\n\n<p>Seis meses despu\u00e9s de la separaci\u00f3n oficial de Shakira y Gerard Piqu\u00e9 sali\u00f3 a la luz un dato que nadie se imaginaba. Aunque ella\u00a0dio mucha informaci\u00f3n de la ruptura en su canci\u00f3n &#8220;Monoton\u00eda&#8221; parece que prefiri\u00f3 emitir una parte bastante dolorosa, ya que en Espa\u00f1a aseguran que\u00a0<strong>\u00e9l la dej\u00f3 porque no pudo darle una hija, como so\u00f1aba.<\/strong><\/p>\n\n\n\n<p>Medios locales deslizaron que la cantante lo intent\u00f3 hasta \u00faltimo momento, y por eso fue vista en una cl\u00ednica de fertilizaci\u00f3n en varias oportunidades. Sin embargo, ninguno de los tratamientos tuvo \u00e9xito y eso la fue alejando del deportista, que ahora sue\u00f1a con ser padre nuevamente acompa\u00f1ado de su nueva novia Clara Ch\u00eda Marti.<\/p>\n\n\n\n<p>Con Shakira, el exdefensor del Barcelona tuvo a Milan y Sasha, que por estas horas se est\u00e1n despidiendo de sus amigos y abuelos paternos para empezar una nueva vida en Miami, lejos de los paparazzi que todos los d\u00edas los esperan en la puerta de su casa para saber sus padres se hablan o no.eeeee<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La versi\u00f3n de Shakira: por qu\u00e9 Gerard Piqu\u00e9 la abandon\u00f3<\/h2>\n\n\n\n<p>A fines de octubre,\u00a0 Shakira decidi\u00f3 sincerarse sobre\u00a0su separaci\u00f3n de Gerard Pique, con quien estuvo en pareja durante 12 a\u00f1os. Cuatro meses despu\u00e9s del\u00a0<strong>comunicado de prensa en el que anunciaron la ruptura<\/strong>, lanz\u00f3 &#8220;Monotonia&#8221; una bachata a duo con Ozuna donde dio detalles del momento en el que el futbolista decidi\u00f3 alejarse para siempre de ella.<\/p>\n\n\n\n<p>En la grabaci\u00f3n, a la colombiana se la ve con un agujero en el pecho tras un disparo recibido de un hombre vestido exactamente igual al futbolista en \u201cMe enamor\u00e9\u201d, el videoclip de la canci\u00f3n que le dedic\u00f3 en 2017.<\/p>\n\n\n\n<p>Shakira hundi\u00f3 al defensor del Barcelona por c\u00f3mo la trat\u00f3 en la recta final de su historia de amor. \u201cDe repente ya no eras el mismo,\u00a0<strong>me dejaste por tu narcisismo.\u00a0<\/strong>T\u00fa no dabas ni la mitad, pero s\u00ed s\u00e9 que\u00a0<strong>di m\u00e1s que t\u00fa<\/strong>.\u00a0<strong>Estaba corriendo por alguien que por m\u00ed ni estaba caminando.\u00a0<\/strong>Te lo digo con sinceridad, t\u00fa estas fr\u00edo como en Navidad. Es mejor que esto se acabe ya. Siempre buscando protagonismo, y te olvidaste de lo que un d\u00eda fuimos. No fue culpa tuya, ni tampoco m\u00eda, fue culpa de la monoton\u00eda\u201d, enton\u00f3 envuelta en un mar de l\u00e1grimas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cantante ten\u00eda muchas ganas de cumplirle el deseo al futbolista, y se someti\u00f3 a varios tratamientos que no funcionaron. Seis meses despu\u00e9s de la separaci\u00f3n oficial de Shakira y&hellip; <\/p>\n","protected":false},"author":8,"featured_media":30109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-30107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=30107"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30107\/revisions"}],"predecessor-version":[{"id":30110,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30107\/revisions\/30110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/30109"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=30107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=30107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=30107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}