{"id":30710,"date":"2022-12-29T15:47:43","date_gmt":"2022-12-29T18:47:43","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=30710"},"modified":"2022-12-29T21:21:30","modified_gmt":"2022-12-30T00:21:30","slug":"cecilia-moreau-pidio-tratar-de-forma-urgente-el-plan-de-pago-de-deuda-previsional","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/nacionales\/cecilia-moreau-pidio-tratar-de-forma-urgente-el-plan-de-pago-de-deuda-previsional\/","title":{"rendered":"Cecilia Moreau pidi\u00f3 tratar de forma urgente el Plan de Pago de Deuda Previsional"},"content":{"rendered":"\n<p>El Plan de Pago de Deuda Previsional afecta a 800 mil personas que no re\u00fanen los 30 a\u00f1os de aportes para jubilarse.<\/p>\n\n\n\n<p>La Presidenta de la C\u00e1mara de Diputados,&nbsp;<strong>Cecilia Moreau<\/strong>, abog\u00f3 por el urgente tratamiento y aprobaci\u00f3n del<strong>&nbsp;Plan de pago de Deuda Previsional<\/strong>, un proyecto que cuenta con media sanci\u00f3n del Senado, y que afecta a casi 800 mil personas que cobrar\u00e1n la&nbsp;<strong>jubilaci\u00f3n m\u00ednima&nbsp;<\/strong>a partir del 1 de enero.<\/p>\n\n\n\n<p>A trav\u00e9s de sus redes sociales, Moreau se\u00f1alo que \u201cla C\u00e1mara de Diputados tiene una veintena de proyectos por tratar, entre los que se encuentra el Plan de Pago de Deuda Previsional por la que casi 800 mil personas ver\u00e1n reducidas al m\u00ednimo sus jubilaciones desde el 1 de enero\u201d.<\/p>\n\n\n\n<p>En ese sentido, agreg\u00f3 que \u201c<strong>en la \u00faltima sesi\u00f3n, no logramos alcanzar el qu\u00f3rum para aprobar esta ley, que ya tiene media sanci\u00f3n del Senado,<\/strong>&nbsp;por mezquindades que algunos todav\u00eda no pueden resolver ni explicar\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Como Presidenta de la Honorable C\u00e1mara de Diputados de la Naci\u00f3n me comprometo a redoblar los esfuerzos para seguir trabajando en este y otros proyectos que quedaron pendientes para mejorar la calidad de vida de todos los argentinos y argentinas.<\/p>&mdash; Cecilia Moreau (@ceciliamoreauok) <a href=\"https:\/\/twitter.com\/ceciliamoreauok\/status\/1607900687584608256?ref_src=twsrc%5Etfw\">December 28, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Asimismo, la titular de la C\u00e1mara baja sostuvo en su posteo que \u201cpor eso es necesario que todas las fuerzas pol\u00edticas trabajemos para resolver los problemas reales de los argentinos y argentinas y que a trav\u00e9s del di\u00e1logo avancemos en soluciones concretas\u201d.<\/p>\n\n\n\n<p>\u201c<strong>El Plan de Pago de Deuda Previsional es una ley que necesitamos aprobar de manera urgente para que miles de ciudadanos que todav\u00eda no re\u00fanen los 30 a\u00f1os de aportes puedan percibir lo que les corresponde y que podemos solucionar en un debate democr\u00e1tico, abierto y federal<\/strong>\u201d, asever\u00f3 Moreau<\/p>\n\n\n\n<p>Adem\u00e1s, enfatiz\u00f3 que \u201ccomo Presidenta de la Honorable C\u00e1mara de Diputados de la Naci\u00f3n me comprometo a redoblar los esfuerzos para seguir trabajando en este y otros proyectos que quedaron pendientes para mejorar la calidad de vida de todos los argentinos y argentinas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Plan de Pago de Deuda Previsional afecta a 800 mil personas que no re\u00fanen los 30 a\u00f1os de aportes para jubilarse. La Presidenta de la C\u00e1mara de Diputados,&nbsp;Cecilia Moreau,&hellip; <\/p>\n","protected":false},"author":8,"featured_media":30759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-30710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=30710"}],"version-history":[{"count":2,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30710\/revisions"}],"predecessor-version":[{"id":30776,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/30710\/revisions\/30776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/30759"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=30710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=30710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=30710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}