{"id":31610,"date":"2023-01-03T22:49:37","date_gmt":"2023-01-04T01:49:37","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=31610"},"modified":"2023-01-03T22:49:40","modified_gmt":"2023-01-04T01:49:40","slug":"la-dpec-realizara-trabajos-de-mejoras-en-saladas-y-mburucuya","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/la-dpec-realizara-trabajos-de-mejoras-en-saladas-y-mburucuya\/","title":{"rendered":"La DPEC realizar\u00e1 trabajos de mejoras en Saladas y Mburucuy\u00e1"},"content":{"rendered":"\n<p>La Direcci\u00f3n Provincial de Energ\u00eda de Corrientes (DPEC) informa que con motivo de realizar mejoras en el servicio, este mi\u00e9rcoles se ejecutar\u00e1n tareas de mantenimiento en equipos de Media Tensi\u00f3n, por lo cual se interrumpir\u00e1 el suministro de energ\u00eda el\u00e9ctrica en las localidades de Mburucuy\u00e1 (GEPO) y Saladas (Pago de los Deseos, Pago Alegre, La Mansi\u00f3n y Santo Domingo). De esta manera, el corte del servicio ser\u00e1 desde las 7 a las 8 horas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"974\" height=\"1024\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2023\/01\/9cec219f890036a8fea4b4777dac6e42f08fed87-974x1024.jpg\" alt=\"\" class=\"wp-image-31611\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2023\/01\/9cec219f890036a8fea4b4777dac6e42f08fed87-974x1024.jpg 974w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2023\/01\/9cec219f890036a8fea4b4777dac6e42f08fed87-285x300.jpg 285w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2023\/01\/9cec219f890036a8fea4b4777dac6e42f08fed87-768x807.jpg 768w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2023\/01\/9cec219f890036a8fea4b4777dac6e42f08fed87.jpg 1218w\" sizes=\"auto, (max-width: 974px) 100vw, 974px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Provincial de Energ\u00eda de Corrientes (DPEC) informa que con motivo de realizar mejoras en el servicio, este mi\u00e9rcoles se ejecutar\u00e1n tareas de mantenimiento en equipos de Media Tensi\u00f3n,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":31612,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/31610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=31610"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/31610\/revisions"}],"predecessor-version":[{"id":31613,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/31610\/revisions\/31613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/31612"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=31610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=31610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=31610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}