{"id":36473,"date":"2023-01-30T17:35:45","date_gmt":"2023-01-30T20:35:45","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=36473"},"modified":"2023-01-30T17:35:49","modified_gmt":"2023-01-30T20:35:49","slug":"julieta-prandi-sobre-su-ex-marido-lo-voy-aplastar-como-una-cucaracha","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/julieta-prandi-sobre-su-ex-marido-lo-voy-aplastar-como-una-cucaracha\/","title":{"rendered":"Julieta Prandi sobre su ex marido: &#8220;Lo voy aplastar como una cucaracha&#8221;"},"content":{"rendered":"\n<p>La modelo y conductora habl\u00f3 del padre de sus hijos, a quien denunci\u00f3 por hostigamiento, violencia sexual y familiar.<\/p>\n\n\n\n<p>Julieta Prandi&nbsp;volvi\u00f3 a referirse a&nbsp;Claudio Contardi,&nbsp;su exmarido, y fue contundente con sus declaraciones. Lo cierto es que en octubre de 2022, se conoci\u00f3 la pericia a la modelo y esta revel\u00f3 hostigamiento, violencia sexual y familiar, motivo por el que pidieron hasta 50 a\u00f1os de c\u00e1rcel para el pap\u00e1 de sus dos hijos.<\/p>\n\n\n\n<p>&#8220;Descubr\u00ed que era pai umbanda. Tuve todo tipo de amenazas en mi vida. Durante cuatro a\u00f1os no vi a mis padres por ejemplo. No me dejaba ver a mis padres&#8221;, record\u00f3 consternada.<\/p>\n\n\n\n<p>Prandi dijo que en los tres a\u00f1os que estuvieron juntos&nbsp;&#8220;perd\u00ed el control completo de mi vida.&nbsp;Lo lleva a la Justicia porque tiene que haber consecuencias.&nbsp;No puede haber tanta impunidad. No se puede perdonar todo. Me da\u00f1\u00f3 emocionalmente, psicol\u00f3gicamente, econ\u00f3micamente&nbsp;&#8220;, dijo en di\u00e1logo con Mar\u00eda Laura Santill\u00e1n.<\/p>\n\n\n\n<p>La modelo y conductora record\u00f3\u00a0&#8220;c\u00f3mo arranc\u00f3 todo&#8221;. &#8220;Empieza con un celo controlador muy extra\u00f1o. Con la ropa. Con las llamadas. He escuchado a muchas mujeres que no las dejaban manejar. Esto permit\u00eda tener un radar de control, te llevo, te traigo. Y poder pispear a d\u00f3nde vas, c\u00f3mo. El argumento siempre es el cuidado, para que no te pase nada. Y te va aislando. Este es un patr\u00f3n que todas lo cuentan. Quedan cada vez m\u00e1s alejadas de la familia&#8221;, cont\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, asegur\u00f3 que va a recuperar todo lo que construy\u00f3: &#8220;\u00c9l no puso un peso para lo que yo constru\u00ed. Es todo fruto de mi esfuerzo porque a m\u00ed nadie me regal\u00f3 nada. Yo hace 23 a\u00f1os que trabajo y est\u00e1 todo, no tengo nada que ocultar. Es todo m\u00e9rito m\u00edo&#8221;, se\u00f1al\u00f3. Y concluy\u00f3: &#8220;Lo voy a aplastar c\u00f3mo una cucaracha&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La modelo y conductora habl\u00f3 del padre de sus hijos, a quien denunci\u00f3 por hostigamiento, violencia sexual y familiar. Julieta Prandi&nbsp;volvi\u00f3 a referirse a&nbsp;Claudio Contardi,&nbsp;su exmarido, y fue contundente con&hellip; <\/p>\n","protected":false},"author":8,"featured_media":36474,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-36473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/36473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=36473"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/36473\/revisions"}],"predecessor-version":[{"id":36475,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/36473\/revisions\/36475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/36474"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=36473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=36473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=36473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}