{"id":38641,"date":"2023-02-07T16:03:28","date_gmt":"2023-02-07T19:03:28","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=38641"},"modified":"2023-02-07T16:03:31","modified_gmt":"2023-02-07T19:03:31","slug":"el-coprodis-entrego-sillas-de-ruedas-y-bastones-para-monte-caseros","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/el-coprodis-entrego-sillas-de-ruedas-y-bastones-para-monte-caseros\/","title":{"rendered":"El COPRODIS entreg\u00f3 sillas de ruedas y bastones para Monte Caseros"},"content":{"rendered":"\n<p>El Ministerio de Desarrollo Social contin\u00faa con entregas de elementos ortop\u00e9dicos para personas con discapacidad a trav\u00e9s del Consejo Provincial de Discapacidad de Corrientes (COPRODIS).<\/p>\n\n\n\n<p>Este martes 7, por la ma\u00f1ana Roxana Tannuri, responsable del COPRODIS, en un trabajo articulado con la directora&nbsp;de Discapacidad de Monte Casero, Laura Viera, realiz\u00f3 la&nbsp;entrega de sillas de ruedas, bastones para adultos y pa\u00f1ales para personas con discapacidad de la localidad, que no poseen cobertura social.<\/p>\n\n\n\n<p>Asimismo, durante el encuentro las Directoras de ambos organismos&nbsp;dialogaron y planificaron asesoramientos y capacitaciones para fortalecer a las familias casere\u00f1as.<\/p>\n\n\n\n<p>El COPRODIS contin\u00faa trabajando de forma articulada con los municipios de la provincia en pos de fortalecer y beneficiar a las familias del interior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Desarrollo Social contin\u00faa con entregas de elementos ortop\u00e9dicos para personas con discapacidad a trav\u00e9s del Consejo Provincial de Discapacidad de Corrientes (COPRODIS). Este martes 7, por la&hellip; <\/p>\n","protected":false},"author":8,"featured_media":38642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/38641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=38641"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/38641\/revisions"}],"predecessor-version":[{"id":38643,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/38641\/revisions\/38643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/38642"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=38641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=38641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=38641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}