{"id":8461,"date":"2022-10-04T11:44:25","date_gmt":"2022-10-04T14:44:25","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=8461"},"modified":"2022-10-04T11:44:29","modified_gmt":"2022-10-04T14:44:29","slug":"corredor-jesuitico-guarani-la-apuesta-turistica-correntina-que-mira-al-exterior","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/sociales\/corredor-jesuitico-guarani-la-apuesta-turistica-correntina-que-mira-al-exterior\/","title":{"rendered":"Corredor Jesu\u00edtico- Guaran\u00ed: la apuesta tur\u00edstica correntina que mira al exterior"},"content":{"rendered":"\n<p>Son nueve las localidades correntinas que componen el circuito cargado de historia que busca sumarse a la oferta local.<\/p>\n\n\n\n<p>El Corredor Jesu\u00edtico- Guaran\u00ed es parte de una antigua ruta que los jesuitas utilizaban en nuestra provincia y se encamina a ser una de las grandes apuestas que el Gobierno provincial busca potenciar a trav\u00e9s de la Feria Internacional del Turismo.<\/p>\n\n\n\n<p>Se trata de un extenso camino que en la provincia comprende &#8220;unos 350 kil\u00f3metros y abarca a nueve localidades&#8221;, explic\u00f3 Sonia Berwanger, delegada regional de Turismo de la Provincia de Corrientes.<\/p>\n\n\n\n<p>El circuito lo integran &#8220;Yapey\u00fa, La Cruz, Alvear, Santo Tom\u00e9, San Carlos, Virasoro, Garruchos y Garab\u00ed&#8221;, dijo la funcionaria quien explic\u00f3 que &#8220;este camino tambi\u00e9n es una ruta de apertura a la yerbamate, es un todo para potenciar la provincia&#8221;.<\/p>\n\n\n\n<p>&#8220;Desde el Gobierno pensamos que la gesti\u00f3n p\u00fablico- privado va de la mano para ayudar a los proyectos tur\u00edsticos junto al Iber\u00e1&#8221; como una alternativa a turistas del exterior.<\/p>\n\n\n\n<p>&#8220;Estamos hablando de turismo rural, aventura, religioso, educativo&#8221;, adem\u00e1s de &#8220;la oferta gastron\u00f3mica, las playas y el carnaval&#8221;, afirm\u00f3 a Punto de Referencia.<\/p>\n\n\n\n<p>&#8220;Estamos realizando capacitaciones en los municipios que integran este corredor, para hacerles entender lo importante del sentido de pertenencia y conocer el lugar en el que estamos viviendo&#8221; para poder explotarlo como una alternativa hacia afuera.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son nueve las localidades correntinas que componen el circuito cargado de historia que busca sumarse a la oferta local. El Corredor Jesu\u00edtico- Guaran\u00ed es parte de una antigua ruta que&hellip; <\/p>\n","protected":false},"author":4,"featured_media":8462,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-8461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/8461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=8461"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/8461\/revisions"}],"predecessor-version":[{"id":8472,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/8461\/revisions\/8472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/8462"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=8461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=8461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=8461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}